{"id":5315,"date":"2024-06-13T13:50:57","date_gmt":"2024-06-13T11:50:57","guid":{"rendered":"https:\/\/getsix-golf-trophy.eu\/?p=5315"},"modified":"2024-06-14T11:32:40","modified_gmt":"2024-06-14T09:32:40","slug":"eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen","status":"publish","type":"post","link":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/","title":{"rendered":"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen"},"content":{"rendered":"<p>Wir laden alle Interessierten ein, sich f\u00fcr unsere Golfveranstaltung anzumelden. <\/p>\n<p>Die <strong>12. Edition des getsix\u00ae Golf Trophy<\/strong> findet am <strong>22. Juni 2024<\/strong> auf dem malerischen Gel\u00e4nde des Gradi Golf Clubs<br \/>\n(Brze\u017ano 1, 55-110 Prusice) statt. <\/p>\n<p>Wir ermutigen alle Interessierten, sich f\u00fcr das Turnier anzumelden und daran teilzunehmen. W\u00e4hrend des getsix\u00ae Golf Trophy haben die Teilnehmer nicht nur die M\u00f6glichkeit, gegen andere Spieler anzutreten, sondern auch neue Gesch\u00e4ftskontakte zu kn\u00fcpfen, Freunde zu treffen und den einzigartigen Geist der Golf-Community zu genie\u00dfen. <\/p>\n<p>Das Turnier offen f\u00fcr Spieler, die dem <strong>PZ Golf angeschlossen<\/strong> sind, und wird unter der professionellen Aufsicht von Richtern durchgef\u00fchrt. Erfahrene Golfer haben die M\u00f6glichkeit, um einzigartige Troph\u00e4en zu spielen, die speziell f\u00fcr diesen Anlass von dem gesch\u00e4tzten K\u00fcnstler Prof. Przemys\u0142aw Tyszkiewicz von der Akademie der Sch\u00f6nen K\u00fcnste in Wroc\u0142aw entworfen wurden. <\/p>\n<p>Die Anmeldungen k\u00f6nnen auf der Website des PZ Golf vorgenommen werden. Die \u00d6ffnung der Teilnahme f\u00fcr ein breites Teilnehmerfeld macht das getsix\u00ae Golf Trophy zu einer hervorragenden Gelegenheit nicht nur f\u00fcr sportlichen Wettbewerb, sondern auch f\u00fcr Integration unter Golfliebhabern. <\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\" href=\"https:\/\/eagle2.pzgolf.pl\/tournament\/v317\/#\/10622\/info\" target=\"_blank\" rel=\"noopener\"><span class=\"elementor-button-content-wrapper\"><span class=\"elementor-button-text\">Anmelden bei PZGolf<\/span><\/span><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Unabh\u00e4ngig vom Kenntnisstand laden wir herzlich zur aktiven Teilnahme am getsix\u00ae Golf Trophy ein. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir laden alle Interessierten ein, sich f\u00fcr unsere Golfveranstaltung anzumelden. Die 12. Edition des getsix\u00ae Golf Trophy findet am 22. Juni 2024 auf dem malerischen Gel\u00e4nde des Gradi Golf Clubs (Brze\u017ano 1, 55-110 Prusice) statt. Wir ermutigen alle Interessierten, sich f\u00fcr das Turnier anzumelden und daran teilzunehmen. W\u00e4hrend des getsix\u00ae Golf Trophy haben die Teilnehmer [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-5315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-getsix-golf-trophy-aktuelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen<\/title>\n<meta name=\"description\" content=\"Wir laden alle Interessierten ein, sich f\u00fcr unsere getsix\u00ae Golf Trophy anzumelden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen\" \/>\n<meta property=\"og:description\" content=\"Wir laden alle Interessierten ein, sich f\u00fcr unsere getsix\u00ae Golf Trophy anzumelden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/\" \/>\n<meta property=\"og:site_name\" content=\"getsix\u00ae Golf Trophy\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-13T11:50:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-14T09:32:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/06\/otwarcie-zapisow-DE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen\",\"datePublished\":\"2024-06-13T11:50:57+00:00\",\"dateModified\":\"2024-06-14T09:32:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/otwarcie-zapisow-DE.jpg\",\"articleSection\":[\"getsix Golf Trophy aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/\",\"url\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/\",\"name\":\"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/otwarcie-zapisow-DE.jpg\",\"datePublished\":\"2024-06-13T11:50:57+00:00\",\"dateModified\":\"2024-06-14T09:32:40+00:00\",\"description\":\"Wir laden alle Interessierten ein, sich f\u00fcr unsere getsix\u00ae Golf Trophy anzumelden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/otwarcie-zapisow-DE.jpg\",\"contentUrl\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/otwarcie-zapisow-DE.jpg\",\"width\":730,\"height\":410,\"caption\":\"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/\",\"name\":\"getsix\u00ae Golf Trophy\",\"description\":\"getsix\u00ae Golf Trophy\",\"publisher\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/#organization\",\"name\":\"getsix\u00ae\",\"url\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/getsix-golf-trophy-logo.webp\",\"contentUrl\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/getsix-golf-trophy-logo.webp\",\"width\":843,\"height\":843,\"caption\":\"getsix\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/getsix-golf-trophy.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen","description":"Wir laden alle Interessierten ein, sich f\u00fcr unsere getsix\u00ae Golf Trophy anzumelden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/","og_locale":"de_DE","og_type":"article","og_title":"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen","og_description":"Wir laden alle Interessierten ein, sich f\u00fcr unsere getsix\u00ae Golf Trophy anzumelden.","og_url":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/","og_site_name":"getsix\u00ae Golf Trophy","article_published_time":"2024-06-13T11:50:57+00:00","article_modified_time":"2024-06-14T09:32:40+00:00","og_image":[{"width":730,"height":410,"url":"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/06\/otwarcie-zapisow-DE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/#article","isPartOf":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/"},"author":{"name":"","@id":""},"headline":"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen","datePublished":"2024-06-13T11:50:57+00:00","dateModified":"2024-06-14T09:32:40+00:00","mainEntityOfPage":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/"},"wordCount":223,"publisher":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/#organization"},"image":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/#primaryimage"},"thumbnailUrl":"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/06\/otwarcie-zapisow-DE.jpg","articleSection":["getsix Golf Trophy aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/","url":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/","name":"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen","isPartOf":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/#primaryimage"},"image":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/#primaryimage"},"thumbnailUrl":"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/06\/otwarcie-zapisow-DE.jpg","datePublished":"2024-06-13T11:50:57+00:00","dateModified":"2024-06-14T09:32:40+00:00","description":"Wir laden alle Interessierten ein, sich f\u00fcr unsere getsix\u00ae Golf Trophy anzumelden.","breadcrumb":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/#primaryimage","url":"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/06\/otwarcie-zapisow-DE.jpg","contentUrl":"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/06\/otwarcie-zapisow-DE.jpg","width":730,"height":410,"caption":"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen"},{"@type":"BreadcrumbList","@id":"https:\/\/getsix-golf-trophy.eu\/de\/eroeffnung-der-anmeldungen-fuer-spieler-die-dem-pz-golf-angeschlossen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/getsix-golf-trophy.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Er\u00f6ffnung der Anmeldungen f\u00fcr Spieler, die dem PZ Golf angeschlossen"}]},{"@type":"WebSite","@id":"https:\/\/getsix-golf-trophy.eu\/de\/#website","url":"https:\/\/getsix-golf-trophy.eu\/de\/","name":"getsix\u00ae Golf Trophy","description":"getsix\u00ae Golf Trophy","publisher":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/getsix-golf-trophy.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/getsix-golf-trophy.eu\/de\/#organization","name":"getsix\u00ae","url":"https:\/\/getsix-golf-trophy.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/getsix-golf-trophy.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/08\/getsix-golf-trophy-logo.webp","contentUrl":"https:\/\/getsix-golf-trophy.eu\/wp-content\/uploads\/2024\/08\/getsix-golf-trophy-logo.webp","width":843,"height":843,"caption":"getsix\u00ae"},"image":{"@id":"https:\/\/getsix-golf-trophy.eu\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/posts\/5315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/comments?post=5315"}],"version-history":[{"count":4,"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/posts\/5315\/revisions"}],"predecessor-version":[{"id":5350,"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/posts\/5315\/revisions\/5350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/media\/5326"}],"wp:attachment":[{"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/media?parent=5315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/categories?post=5315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/getsix-golf-trophy.eu\/de\/wp-json\/wp\/v2\/tags?post=5315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}